{"id":2839,"date":"2022-09-30T08:49:34","date_gmt":"2022-09-30T06:49:34","guid":{"rendered":"https:\/\/pour-enfants.fr\/charades\/?p=2839"},"modified":"2022-09-30T09:31:40","modified_gmt":"2022-09-30T07:31:40","slug":"halloween-dessin-de-fantome-quadrillage-imprimer-reproduction","status":"publish","type":"post","link":"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/","title":{"rendered":"Halloween dessin fant\u00f4me. Reproduction sur quadrillage. Coloriage."},"content":{"rendered":"<p><strong>Halloween dessin fant\u00f4me<\/strong><strong>.<\/strong> Avec plein de dessins de fant\u00f4mes \u00e0 reproduire, imprimer ou recopier.<\/p>\n<p>Pour Halloween, je vous propose trois fiches \u00e0 imprimer avec des dessins de\u00a0 fant\u00f4mes et une frise. La reproduction de ces dessins est vraiment facile. Elle peut se faire sur une feuille de cahier \u00e0 carreaux ou une feuille quadrill\u00e9e.<\/p>\n<h2>Halloween. Dessin de fant\u00f4me sur quadrillage.<\/h2>\n<figure id=\"attachment_2833\" aria-describedby=\"caption-attachment-2833\" style=\"width: 499px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-1.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" class=\"wp-image-2833 \" title=\"Halloween. Dessin de fant\u00f4me sur quadrillage. Reproduction. Coloriage \u00e0 imprimer. Gratuit.\" src=\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-1.png\" alt=\"coloriage Halloween fantome dessin sur quadrillage reproduction\" width=\"499\" height=\"719\" srcset=\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-1.png 600w, https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-1-208x300.png 208w\" sizes=\"(max-width: 499px) 100vw, 499px\" \/><\/a><figcaption id=\"caption-attachment-2833\" class=\"wp-caption-text\">Halloween. Dessin de fant\u00f4me. Reproduction facile sur quadrillage. On peut aussi reproduire l&#8217;image du fant\u00f4me \u00e0 main lev\u00e9e sur feuille de cahier \u00e0 carreaux. Ou sur feuille quadrill\u00e9e. Pour enfants.<\/figcaption><\/figure>\n<p>Copier, ou recopier un dessin, c&#8217;est bien s\u00fbr en faire la reproduction, le reproduire. Les dessins de fant\u00f4mes que je vous propose ont des formes simples. Il sera facile de les utiliser pour faire des activit\u00e9s avec les enfants.<\/p>\n<p>Dessiner sur quadrillage fait partie de la g\u00e9om\u00e9trie. Les enfants trouvent \u00e7a rigolo. C&#8217;est encore plus dr\u00f4le si on le fait pendant Halloween, sur le th\u00e8me des fant\u00f4mes, sorci\u00e8res ou autres monstres.<\/p>\n<figure id=\"attachment_2834\" aria-describedby=\"caption-attachment-2834\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-2.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" class=\"wp-image-2834\" title=\"Halloween fantome dessin sur quadrillage. Reproduction ou coloriage.\" src=\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-2.png\" alt=\"coloriage Halloween fantome dessin sur quadrillage a reproduire\" width=\"500\" height=\"690\" \/><\/a><figcaption id=\"caption-attachment-2834\" class=\"wp-caption-text\">Halloween Fant\u00f4me facile \u00e0 dessiner. Reproduction facile sur quadrillage. On peut aussi reproduire l&#8217;image du fant\u00f4me \u00e0 main lev\u00e9e sur feuille de cahier \u00e0 carreaux. Ou sur feuille quadrill\u00e9e. Pour enfants.<\/figcaption><\/figure>\n<p><strong>Halloween dessin fant\u00f4me.<\/strong> La reproduction en est tr\u00e8s facile. Le dessin contient uniquement quelques traits et des portions de cercles.<\/p>\n<figure id=\"attachment_2835\" aria-describedby=\"caption-attachment-2835\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-chien.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" class=\"wp-image-2835\" title=\"Halloween. Dessin de fant\u00f4me chien. Reproduction facile sur quadrillage. \" src=\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-chien.png\" alt=\"coloriage Halloween fantome chien dessin reproduction sur quadrillage\" width=\"501\" height=\"729\" \/><\/a><figcaption id=\"caption-attachment-2835\" class=\"wp-caption-text\">Halloween. Dessin de fant\u00f4me chien. Reproduction facile sur quadrillage. L&#8217;image du fant\u00f4me est facile \u00e0 reproduire sur feuille de cahier \u00e0 carreaux ou sur feuille quadrill\u00e9e. Pour enfants.<\/figcaption><\/figure>\n<p>Pour moi ce dessin \u00e9voque un chien. Mais comme c&#8217;est un fant\u00f4me, il peut sugg\u00e9rer tout autre animal.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_2830\" aria-describedby=\"caption-attachment-2830\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-frises-cercles.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" class=\"wp-image-2830\" title=\"Halloween. Dessin de frise \u00e0 reproduire. Pour faire des dessins de fant\u00f4mes. Frises \u00e0 base de cercles.\" src=\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-frises-cercles.png\" alt=\"frise halloween sur quadrillage dessins de fant\u00f4mes vagues\" width=\"500\" height=\"785\" \/><\/a><figcaption id=\"caption-attachment-2830\" class=\"wp-caption-text\">Halloween. Dessin de frise \u00e0 reproduire. Pour faire des dessins de fant\u00f4mes par exemple. Frises \u00e0 base de cercles. Reproduction facile sur quadrillage. Pour enfants.<\/figcaption><\/figure>\n<p>J&#8217;ai utilis\u00e9 des dessins de cercles pour dessiner mes petits fant\u00f4mes rigolos. Ce qui m&#8217;a inspir\u00e9 les mod\u00e8les de frises ci-dessus.<\/p>\n<h3>D&#8217;autres activit\u00e9s de reproduction sur quadrillage<\/h3>\n<p><a href=\"https:\/\/pour-enfants.fr\/charades\/coloriage-sur-quadrillage-halloween-vampire\/\" target=\"_blank\" rel=\"noopener\">Coloriage de vampire Halloween<\/a><\/p>\n<p>Ce dessin de vampire Halloween a beaucoup de succ\u00e8s sur Pinterest.<\/p>\n<p><a href=\"https:\/\/pour-enfants.fr\/charades\/coloriage-sur-quadrillage-halloween-chauve-souris\/\" target=\"_blank\" rel=\"noopener\">Coloriage de chauve-souris Halloween<\/a><\/p>\n<p>Une image de chauve-souris rigolote au graphisme tr\u00e8s minimaliste.<\/p>\n<p>Avec l&#8217;aide de carreaux, on peut agrandir facilement un dessin. Il faut utiliser une feuille avec de plus grands carreaux. Le contenu d&#8217;un petit carreau sera reproduit sur un carreau de plus grande taille. Facile&#160;!<\/p>\n<p>Reproduire ou copier un dessin, c&#8217;est la m\u00eame chose. On appelle cela de la reproduction sur quadrillage. Dessin ou image, ce sont deux mots proches.<\/p>\n<p><a href=\"https:\/\/pour-enfants.fr\/charades\/coloriage-halloween-quadrillage-chat\/\" target=\"_blank\" rel=\"noopener\">Reproduction sur quadrillage. Un dessin de chat.<\/a><\/p>\n<h3>Des jeux et activit\u00e9s pour f\u00eater Halloween<\/h3>\n<p><a href=\"https:\/\/www.jeux-halloween.pour-enfants.fr\/\" target=\"_blank\" rel=\"noopener\">Jeux d&#8217;Halloween. Petits bricolages faciles.<\/a><\/p>\n<p>Les jeux de Baba Loween la petite sorci\u00e8re. Pour les enfants des classes de maternelle et \u00e9l\u00e9mentaire.<\/p>\n<p><a href=\"http:\/\/www.jeux-halloween.pour-enfants.fr\/blagues\/blague.htm\" target=\"_blank\" rel=\"noopener\">Blagues et devinettes d&#8217;Halloween<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Halloween dessin fant\u00f4me. Avec plein de dessins de fant\u00f4mes \u00e0 reproduire, imprimer ou recopier. Pour Halloween, je vous propose trois fiches \u00e0 imprimer avec des dessins de\u00a0 fant\u00f4mes et une frise. La reproduction de ces dessins est vraiment facile. Elle peut se faire sur une feuille de cahier \u00e0 carreaux ou une feuille quadrill\u00e9e. Halloween. &hellip; <a href=\"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Halloween dessin fant\u00f4me. Reproduction sur quadrillage. Coloriage.<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[462,180,294,254,409,266],"tags":[375,317,313,821,819,401,286,818,822,823,811,820,813],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Halloween dessin fant\u00f4me. Reproduction sur quadrillage. Coloriage.<\/title>\n<meta name=\"description\" content=\"Halloween dessin fant\u00f4me. \u00c0 imprimer pour coloriage. Reproduction sur quadrillage. Activit\u00e9s enfants. G\u00e9om\u00e9trie facile. Fiche gratuite.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Halloween dessin fant\u00f4me. Reproduction sur quadrillage. Coloriage.\" \/>\n<meta property=\"og:description\" content=\"Halloween dessin fant\u00f4me. \u00c0 imprimer pour coloriage. Reproduction sur quadrillage. Activit\u00e9s enfants. G\u00e9om\u00e9trie facile. Fiche gratuite.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/\" \/>\n<meta property=\"og:site_name\" content=\"Charades, mots cach\u00e9s, jeux, devinettes, pour enfants.\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-30T06:49:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-30T07:31:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claude\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pour-enfants.fr\/charades\/#website\",\"url\":\"https:\/\/pour-enfants.fr\/charades\/\",\"name\":\"Charades, mots cach\\u00e9s, jeux, devinettes, pour enfants.\",\"description\":\"Charades, devinettes et jeux de mots pour enfants \\u2014 \\u00e0 imprimer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pour-enfants.fr\/charades\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-1.png\",\"contentUrl\":\"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-1.png\",\"width\":600,\"height\":865,\"caption\":\"Halloween. Dessin de fant\\u00f4me. Reproduction facile sur quadrillage. On peut aussi reproduire l'image du fant\\u00f4me \\u00e0 main lev\\u00e9e sur feuille de cahier \\u00e0 carreaux. Ou sur feuille quadrill\\u00e9e. Pour enfants.\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/#webpage\",\"url\":\"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/\",\"name\":\"Halloween dessin fant\\u00f4me. Reproduction sur quadrillage. Coloriage.\",\"isPartOf\":{\"@id\":\"https:\/\/pour-enfants.fr\/charades\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/#primaryimage\"},\"datePublished\":\"2022-09-30T06:49:34+00:00\",\"dateModified\":\"2022-09-30T07:31:40+00:00\",\"author\":{\"@id\":\"https:\/\/pour-enfants.fr\/charades\/#\/schema\/person\/b4de8aeca5db9012b507269d7bcc884c\"},\"description\":\"Halloween dessin fant\\u00f4me. \\u00c0 imprimer pour coloriage. Reproduction sur quadrillage. Activit\\u00e9s enfants. G\\u00e9om\\u00e9trie facile. Fiche gratuite.\",\"breadcrumb\":{\"@id\":\"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/pour-enfants.fr\/charades\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Halloween dessin fant\\u00f4me. Reproduction sur quadrillage. Coloriage.\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/pour-enfants.fr\/charades\/#\/schema\/person\/b4de8aeca5db9012b507269d7bcc884c\",\"name\":\"Claude\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/pour-enfants.fr\/charades\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6ceb5c7005a756f5cd17a96a0419683b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6ceb5c7005a756f5cd17a96a0419683b?s=96&d=mm&r=g\",\"caption\":\"Claude\"},\"sameAs\":[\"http:\/\/www.pour-enfants.fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Halloween dessin fant\u00f4me. Reproduction sur quadrillage. Coloriage.","description":"Halloween dessin fant\u00f4me. \u00c0 imprimer pour coloriage. Reproduction sur quadrillage. Activit\u00e9s enfants. G\u00e9om\u00e9trie facile. Fiche gratuite.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/","og_locale":"fr_FR","og_type":"article","og_title":"Halloween dessin fant\u00f4me. Reproduction sur quadrillage. Coloriage.","og_description":"Halloween dessin fant\u00f4me. \u00c0 imprimer pour coloriage. Reproduction sur quadrillage. Activit\u00e9s enfants. G\u00e9om\u00e9trie facile. Fiche gratuite.","og_url":"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/","og_site_name":"Charades, mots cach\u00e9s, jeux, devinettes, pour enfants.","article_published_time":"2022-09-30T06:49:34+00:00","article_modified_time":"2022-09-30T07:31:40+00:00","og_image":[{"url":"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-1.png"}],"twitter_card":"summary","twitter_misc":{"\u00c9crit par":"Claude","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/pour-enfants.fr\/charades\/#website","url":"https:\/\/pour-enfants.fr\/charades\/","name":"Charades, mots cach\u00e9s, jeux, devinettes, pour enfants.","description":"Charades, devinettes et jeux de mots pour enfants \u2014 \u00e0 imprimer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pour-enfants.fr\/charades\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-1.png","contentUrl":"https:\/\/pour-enfants.fr\/charades\/wp-content\/uploads\/2022\/09\/coloriage-sur-quadrillage-halloween-fantome-1.png","width":600,"height":865,"caption":"Halloween. Dessin de fant\u00f4me. Reproduction facile sur quadrillage. On peut aussi reproduire l'image du fant\u00f4me \u00e0 main lev\u00e9e sur feuille de cahier \u00e0 carreaux. Ou sur feuille quadrill\u00e9e. Pour enfants."},{"@type":"WebPage","@id":"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/#webpage","url":"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/","name":"Halloween dessin fant\u00f4me. Reproduction sur quadrillage. Coloriage.","isPartOf":{"@id":"https:\/\/pour-enfants.fr\/charades\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/#primaryimage"},"datePublished":"2022-09-30T06:49:34+00:00","dateModified":"2022-09-30T07:31:40+00:00","author":{"@id":"https:\/\/pour-enfants.fr\/charades\/#\/schema\/person\/b4de8aeca5db9012b507269d7bcc884c"},"description":"Halloween dessin fant\u00f4me. \u00c0 imprimer pour coloriage. Reproduction sur quadrillage. Activit\u00e9s enfants. G\u00e9om\u00e9trie facile. Fiche gratuite.","breadcrumb":{"@id":"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pour-enfants.fr\/charades\/halloween-dessin-fantome-quadrillage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pour-enfants.fr\/charades\/"},{"@type":"ListItem","position":2,"name":"Halloween dessin fant\u00f4me. Reproduction sur quadrillage. Coloriage."}]},{"@type":"Person","@id":"https:\/\/pour-enfants.fr\/charades\/#\/schema\/person\/b4de8aeca5db9012b507269d7bcc884c","name":"Claude","image":{"@type":"ImageObject","@id":"https:\/\/pour-enfants.fr\/charades\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/6ceb5c7005a756f5cd17a96a0419683b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ceb5c7005a756f5cd17a96a0419683b?s=96&d=mm&r=g","caption":"Claude"},"sameAs":["http:\/\/www.pour-enfants.fr"]}]}},"_links":{"self":[{"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/posts\/2839"}],"collection":[{"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/comments?post=2839"}],"version-history":[{"count":8,"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/posts\/2839\/revisions"}],"predecessor-version":[{"id":2847,"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/posts\/2839\/revisions\/2847"}],"wp:attachment":[{"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/media?parent=2839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/categories?post=2839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/tags?post=2839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}