{"id":799,"count":2,"description":"","link":"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/","name":"chanson sorciere","slug":"chanson-sorciere","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>chanson sorciere Archives - Charades, mots cach\u00e9s, jeux, devinettes, pour enfants.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"chanson sorciere Archives - Charades, mots cach\u00e9s, jeux, devinettes, pour enfants.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/\" \/>\n<meta property=\"og:site_name\" content=\"Charades, mots cach\u00e9s, jeux, devinettes, pour enfants.\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pour-enfants.fr\/charades\/#website\",\"url\":\"https:\/\/pour-enfants.fr\/charades\/\",\"name\":\"Charades, mots cach\\u00e9s, jeux, devinettes, pour enfants.\",\"description\":\"Charades, devinettes et jeux de mots pour enfants \\u2014 \\u00e0 imprimer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pour-enfants.fr\/charades\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/#webpage\",\"url\":\"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/\",\"name\":\"chanson sorciere Archives - Charades, mots cach\\u00e9s, jeux, devinettes, pour enfants.\",\"isPartOf\":{\"@id\":\"https:\/\/pour-enfants.fr\/charades\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/pour-enfants.fr\/charades\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"chanson sorciere\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"chanson sorciere Archives - Charades, mots cach\u00e9s, jeux, devinettes, pour enfants.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/","og_locale":"fr_FR","og_type":"article","og_title":"chanson sorciere Archives - Charades, mots cach\u00e9s, jeux, devinettes, pour enfants.","og_url":"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/","og_site_name":"Charades, mots cach\u00e9s, jeux, devinettes, pour enfants.","twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/pour-enfants.fr\/charades\/#website","url":"https:\/\/pour-enfants.fr\/charades\/","name":"Charades, mots cach\u00e9s, jeux, devinettes, pour enfants.","description":"Charades, devinettes et jeux de mots pour enfants \u2014 \u00e0 imprimer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pour-enfants.fr\/charades\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"CollectionPage","@id":"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/#webpage","url":"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/","name":"chanson sorciere Archives - Charades, mots cach\u00e9s, jeux, devinettes, pour enfants.","isPartOf":{"@id":"https:\/\/pour-enfants.fr\/charades\/#website"},"breadcrumb":{"@id":"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pour-enfants.fr\/charades\/du-passe\/tag\/chanson-sorciere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pour-enfants.fr\/charades\/"},{"@type":"ListItem","position":2,"name":"chanson sorciere"}]}]}},"_links":{"self":[{"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/tags\/799"}],"collection":[{"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/pour-enfants.fr\/charades\/wp-json\/wp\/v2\/posts?tags=799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}